{"id":13586,"date":"2019-12-26T10:52:08","date_gmt":"2019-12-26T14:52:08","guid":{"rendered":"https:\/\/focus.aw\/?p=13586"},"modified":"2019-12-26T11:55:48","modified_gmt":"2019-12-26T15:55:48","slug":"e-trend-2019","status":"publish","type":"post","link":"https:\/\/focus.aw\/index.php\/2019\/12\/26\/e-trend-2019\/","title":{"rendered":"E TREND 2019"},"content":{"rendered":"\n\n\t\t\t<!-- START slider banner tex 1 REVOLUTION SLIDER 6.7.38 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_20_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:rgba(NaN,186,NaN,0);padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_20_1\" style=\"\" data-version=\"6.7.38\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-116\" data-title=\"Slide\" data-duration=\"12000ms\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"E TREND 2019\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-116-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:70;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:4000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2020\/12\/bohemian-banner-c-274.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-116-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/focus.aw\/index.php\/2026\/07\/06\/focus-digital-342-download-awo\/\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:8000;sp:70;sR:8000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/07\/BANNER-C-342-550-x-110-px.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-116-layer-3\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.garagecentraal.com\/hyundai\/suv\/creta\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:4000;sp:70;sR:4000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:8000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/07\/CR-_FocusBanner_550x110.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-1161\" data-title=\"Slide\" data-duration=\"12000ms\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"E TREND 2019\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-1161-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:70;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:4000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2020\/12\/bohemian-banner-c-274.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-1161-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/focus.aw\/index.php\/2026\/07\/06\/focus-digital-342-download-awo\/\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:8000;sp:70;sR:8000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/07\/BANNER-C-342-550-x-110-px.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-1161-layer-3\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.garagecentraal.com\/hyundai\/suv\/creta\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:4000;sp:70;sR:4000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:8000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/07\/CR-_FocusBanner_550x110.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_20_1',rl:[1240,1024,778,480],el:[110],gw:[550],gh:[110],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider201\"]!==undefined) {window.RS_MODULES.modules[\"revslider201\"].once = false;window.revapi20 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-drop-cap\">E pyjamanan pa Pasco a bira un trend y por mira con dibertido esaki ta mustra pa henter famia bisti mescos pa logra un post festivo pa comparti cu un bunita mensahe Navide\u00f1o. Entre e dise\u00f1onan cu un variedad grandi den e tema di Santa Claus, kerstboom y regalo, a duna e celebracion di Pasco 2019 un toke dibertido. E trend di bisti pyjama pa saca un potret familiar pa share riba social media, ademas di ta fun ta mustra e union familar den e temporada festivo di fin di a\u00f1a.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\t\t\t<!-- START slider banner tex 2 REVOLUTION SLIDER 6.7.38 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_21_2_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_21_2\" style=\"\" data-version=\"6.7.38\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-106\" data-title=\"Slide\" data-duration=\"16000ms\" data-anim=\"adpr:false;ms:70;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"E TREND 2019\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-106-layer-0\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/web.facebook.com\/profile.php?id=61573929849977\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:12000;sp:70;sR:12000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:70;sR:7930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2025\/05\/Hit-94-banner-c.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-106-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.garagecentraal.com\/volkswagen\/suv\/tera\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:4000;sp:70;sR:4000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:8000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/07\/TE-_FocusBanner_550x100.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-106-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:8000;sp:70;sR:8000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:12000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2020\/11\/casa-tua-banner-c-274.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-106-layer-7\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/focus.aw\/index.php\/2026\/07\/06\/focus-digital-342-download-awo\/\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:70;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:4000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/07\/BANNER-C-342-550-x-110-px.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-1061\" data-title=\"Slide\" data-duration=\"16000ms\" data-anim=\"adpr:false;ms:70;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"E TREND 2019\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-1061-layer-0\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/web.facebook.com\/profile.php?id=61573929849977\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:12000;sp:70;sR:12000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:70;sR:7930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2025\/05\/Hit-94-banner-c.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-1061-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.garagecentraal.com\/volkswagen\/suv\/tera\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:4000;sp:70;sR:4000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:8000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/07\/TE-_FocusBanner_550x100.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-1061-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:8000;sp:70;sR:8000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:12000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2020\/11\/casa-tua-banner-c-274.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-1061-layer-7\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/focus.aw\/index.php\/2026\/07\/06\/focus-digital-342-download-awo\/\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:70;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:4000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/07\/BANNER-C-342-550-x-110-px.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_21_2',rl:[1240,1024,778,480],el:[110],gw:[550],gh:[110],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider212\"]!==undefined) {window.RS_MODULES.modules[\"revslider212\"].once = false;window.revapi21 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"546\" height=\"1024\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/c8c9abea-5847-4186-82ff-09c75422cc06-546x1024.jpg\" alt=\"\" class=\"wp-image-13623\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/c8c9abea-5847-4186-82ff-09c75422cc06-546x1024.jpg 546w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/c8c9abea-5847-4186-82ff-09c75422cc06-160x300.jpg 160w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/c8c9abea-5847-4186-82ff-09c75422cc06-224x420.jpg 224w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/c8c9abea-5847-4186-82ff-09c75422cc06.jpg 591w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"820\" height=\"1024\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3561-820x1024.jpg\" alt=\"\" class=\"wp-image-13602\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3561-820x1024.jpg 820w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3561-240x300.jpg 240w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3561-768x959.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3561-696x869.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3561-336x420.jpg 336w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3561.jpg 961w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><\/figure>\n\n\n<div id='gallery-1' class='gallery galleryid-13586 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/focus.aw\/img_3560\/'><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"1186\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3560.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3560.jpg 828w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3560-209x300.jpg 209w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3560-715x1024.jpg 715w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3560-768x1100.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3560-696x997.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3560-293x420.jpg 293w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/focus.aw\/img_3562\/'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3562.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3562.jpg 1200w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3562-300x300.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3562-1024x1024.jpg 1024w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3562-150x150.jpg 150w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3562-768x768.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3562-696x696.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3562-1068x1068.jpg 1068w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3562-420x420.jpg 420w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"756\" height=\"1024\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3571-756x1024.jpg\" alt=\"\" class=\"wp-image-13595\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3571-756x1024.jpg 756w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3571-222x300.jpg 222w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3571-768x1040.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3571-696x943.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3571-310x420.jpg 310w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3571.jpg 813w\" sizes=\"auto, (max-width: 756px) 100vw, 756px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_8556.jpg\" alt=\"\" class=\"wp-image-13616\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_8556.jpg 720w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_8556-225x300.jpg 225w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_8556-696x928.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_8556-315x420.jpg 315w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n<div id='gallery-2' class='gallery galleryid-13586 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/focus.aw\/img_3563\/'><img loading=\"lazy\" decoding=\"async\" width=\"788\" height=\"1200\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3563.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3563.jpg 788w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3563-197x300.jpg 197w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3563-672x1024.jpg 672w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3563-768x1170.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3563-696x1060.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3563-276x420.jpg 276w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/focus.aw\/index.php\/2019\/12\/26\/e-trend-2019\/img_8554\/'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_8554.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_8554.jpg 720w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_8554-225x300.jpg 225w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_8554-696x928.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_8554-315x420.jpg 315w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"909\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/a7f0ee3a-5e2c-4e86-b8e1-48d9f243e637.jpg\" alt=\"\" class=\"wp-image-13622\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/a7f0ee3a-5e2c-4e86-b8e1-48d9f243e637.jpg 591w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/a7f0ee3a-5e2c-4e86-b8e1-48d9f243e637-195x300.jpg 195w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/a7f0ee3a-5e2c-4e86-b8e1-48d9f243e637-273x420.jpg 273w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><\/figure>\n\n\n<div id='gallery-3' class='gallery galleryid-13586 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/focus.aw\/img_3575\/'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3575.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3575.jpg 1200w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3575-300x225.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3575-1024x768.jpg 1024w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3575-768x576.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3575-80x60.jpg 80w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3575-265x198.jpg 265w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3575-696x522.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3575-1068x801.jpg 1068w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3575-560x420.jpg 560w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/focus.aw\/1070cceb-de82-4bdf-85f8-e4cb4cdd1c07\/'><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"933\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/1070cceb-de82-4bdf-85f8-e4cb4cdd1c07.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/1070cceb-de82-4bdf-85f8-e4cb4cdd1c07.jpg 591w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/1070cceb-de82-4bdf-85f8-e4cb4cdd1c07-190x300.jpg 190w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/1070cceb-de82-4bdf-85f8-e4cb4cdd1c07-266x420.jpg 266w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"768\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3567.jpg\" alt=\"\" class=\"wp-image-13592\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3567.jpg 780w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3567-300x295.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3567-768x756.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3567-696x685.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3567-427x420.jpg 427w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/figure>\n\n\n<div id='gallery-4' class='gallery galleryid-13586 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/focus.aw\/img_3570\/'><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"614\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3570.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3570.jpg 828w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3570-300x222.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3570-768x570.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3570-80x60.jpg 80w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3570-265x198.jpg 265w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3570-485x360.jpg 485w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3570-696x516.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3570-566x420.jpg 566w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/focus.aw\/img_3569\/'><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"1165\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3569.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3569.jpg 828w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3569-213x300.jpg 213w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3569-728x1024.jpg 728w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3569-768x1081.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3569-696x979.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3569-299x420.jpg 299w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"897\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/j-IMG_3579.jpg\" alt=\"\" class=\"wp-image-13614\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/j-IMG_3579.jpg 650w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/j-IMG_3579-217x300.jpg 217w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/j-IMG_3579-304x420.jpg 304w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"554\" height=\"980\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3578.jpg\" alt=\"\" class=\"wp-image-13588\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3578.jpg 554w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3578-170x300.jpg 170w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3578-237x420.jpg 237w\" sizes=\"auto, (max-width: 554px) 100vw, 554px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3555-1024x1024.jpg\" alt=\"\" class=\"wp-image-13605\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3555-1024x1024.jpg 1024w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3555-300x300.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3555-150x150.jpg 150w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3555-768x768.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3555-696x696.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3555-1068x1068.jpg 1068w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3555-420x420.jpg 420w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3555.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div id='gallery-5' class='gallery galleryid-13586 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/focus.aw\/lionel-messi\/'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/Lionel-Messi.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/Lionel-Messi.jpg 1200w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/Lionel-Messi-300x300.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/Lionel-Messi-1024x1024.jpg 1024w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/Lionel-Messi-150x150.jpg 150w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/Lionel-Messi-768x768.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/Lionel-Messi-696x696.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/Lionel-Messi-1068x1068.jpg 1068w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/Lionel-Messi-420x420.jpg 420w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/focus.aw\/sarco\/'><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"730\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/sarco.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/sarco.jpg 730w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/sarco-300x300.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/sarco-150x150.jpg 150w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/sarco-696x696.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/sarco-420x420.jpg 420w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-6' class='gallery galleryid-13586 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/focus.aw\/pijama-jlo-a\/'><img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"600\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-jlo-a.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-jlo-a.jpg 612w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-jlo-a-300x294.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-jlo-a-428x420.jpg 428w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/focus.aw\/img_3554\/'><img loading=\"lazy\" decoding=\"async\" width=\"634\" height=\"634\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3554.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3554.jpg 634w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3554-300x300.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3554-150x150.jpg 150w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/IMG_3554-420x420.jpg 420w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<div id='gallery-7' class='gallery galleryid-13586 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/focus.aw\/pijama-karda\/'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"550\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-karda.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-karda.jpg 550w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-karda-300x300.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-karda-150x150.jpg 150w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-karda-420x420.jpg 420w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/focus.aw\/pijama-834x630\/'><img loading=\"lazy\" decoding=\"async\" width=\"834\" height=\"630\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-834x630-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-834x630-1.jpg 834w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-834x630-1-300x227.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-834x630-1-768x580.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-834x630-1-80x60.jpg 80w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-834x630-1-696x526.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2019\/12\/pijama-834x630-1-556x420.jpg 556w\" sizes=\"auto, (max-width: 834px) 100vw, 834px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>E pyjamanan pa Pasco a bira un trend y por mira con dibertido esaki ta mustra pa henter famia bisti mescos pa logra un post festivo pa comparti cu un bunita mensahe Navide\u00f1o. Entre e dise\u00f1onan cu un variedad grandi den e tema di Santa Claus, kerstboom y regalo, a duna e celebracion di Pasco [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":13613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[2,46],"tags":[],"class_list":{"0":"post-13586","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured","8":"category-news-flash"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/posts\/13586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/comments?post=13586"}],"version-history":[{"count":4,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/posts\/13586\/revisions"}],"predecessor-version":[{"id":13627,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/posts\/13586\/revisions\/13627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/media\/13613"}],"wp:attachment":[{"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/media?parent=13586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/categories?post=13586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/tags?post=13586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}