{"id":26952,"date":"2023-03-22T17:35:01","date_gmt":"2023-03-22T21:35:01","guid":{"rendered":"https:\/\/focus.aw\/?p=26952"},"modified":"2023-03-22T18:15:16","modified_gmt":"2023-03-22T22:15:16","slug":"un-oportunidad-destina-pa-jennifer-lopez-na-suisa","status":"publish","type":"post","link":"https:\/\/focus.aw\/index.php\/2023\/03\/22\/un-oportunidad-destina-pa-jennifer-lopez-na-suisa\/","title":{"rendered":"UN OPORTUNIDAD DESTINA PA JENNIFER LOPEZ NA SUISA"},"content":{"rendered":"\n\n\t\t\t<!-- START slider banner tex 1 REVOLUTION SLIDER 6.7.38 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_20_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:rgba(NaN,186,NaN,0);padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_20_1\" style=\"\" data-version=\"6.7.38\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-116\" data-title=\"Slide\" data-duration=\"12000ms\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"UN OPORTUNIDAD DESTINA PA JENNIFER LOPEZ NA SUISA\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-116-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:70;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:4000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2020\/12\/bohemian-banner-c-274.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-116-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/web.facebook.com\/romartradingbeauty\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:8000;sp:70;sR:8000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/05\/550x110_New-Jergens-body-lotion_focus-banner.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-116-layer-3\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.garagecentraal.com\/flying-dress\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:4000;sp:70;sR:4000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:8000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/04\/GC_-_FocusBanner_550x100-copia.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-1161\" data-title=\"Slide\" data-duration=\"12000ms\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"UN OPORTUNIDAD DESTINA PA JENNIFER LOPEZ NA SUISA\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-1161-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:70;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:4000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2020\/12\/bohemian-banner-c-274.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-1161-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/web.facebook.com\/romartradingbeauty\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:8000;sp:70;sR:8000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/05\/550x110_New-Jergens-body-lotion_focus-banner.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-20-slide-1161-layer-3\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.garagecentraal.com\/flying-dress\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:4000;sp:70;sR:4000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:8000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/04\/GC_-_FocusBanner_550x100-copia.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_20_1',rl:[1240,1024,778,480],el:[110],gw:[550],gh:[110],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider201\"]!==undefined) {window.RS_MODULES.modules[\"revslider201\"].once = false;window.revapi20 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Jennifer ta trahando como un Senior Corporate Controller na Amcor, e compania multinacional mas grandi na Suisa, cu ta produci pakete pa diferente sector manera cuminda, medicina y tabaco. E ta revisa e parti financiero di un division pa haci analisis y wak si e compania ta \u2018meet\u2019 su presupuesto y obhetivonan financiero. Si lo a puntra Jennifer tempo e tabata studiando na cua pais e lo kier bay traha, riba su lista e no tabatin Suisa niun momento, pero e ta bisa \u2018by luck of chance\u2019 el a yega eynan <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-1024x768.jpg\" alt=\"\" class=\"wp-image-26954\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-1024x768.jpg 1024w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-300x225.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-768x576.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-696x522.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-1068x801.jpg 1068w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-560x420.jpg 560w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-80x60.jpg 80w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-265x198.jpg 265w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-500x375.jpg 500w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1-800x600.jpg 800w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/Graduation-1.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Despues di a caba VWO na Colegio Arubano, Jennifer a bay studia na Hulanda y a obtene su Bachelor den Bedrijfseconomie na Erasmus Universiteit na Rotterdam. E estudio tabata basta amplio y a duna oportunidad pa Jennifer haya conocemento den diferente aspecto, por ehempel con nos economia ta hinca den otro y cua ta tur e factornan cu ta hunga un rol den maneha un organisacion. E tabata haya interesante pa analisa \u2018financial statements\u2019 di companianan y con esey ta aporta na nan strategia.<\/p>\n\n\n\n\n\t\t\t<!-- START slider banner tex 2 REVOLUTION SLIDER 6.7.38 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_21_2_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_21_2\" style=\"\" data-version=\"6.7.38\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-106\" data-title=\"Slide\" data-duration=\"16000ms\" data-anim=\"adpr:false;ms:70;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"UN OPORTUNIDAD DESTINA PA JENNIFER LOPEZ NA SUISA\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-106-layer-0\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/web.facebook.com\/profile.php?id=61573929849977\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:12000;sp:70;sR:12000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:70;sR:7930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2025\/05\/Hit-94-banner-c.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-106-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.garagecentraal.com\/gac-motor\/aion-ut\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:4000;sp:70;sR:4000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:8000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/05\/GU_-_FocusBanner_550x100.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-106-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:8000;sp:70;sR:8000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:12000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2020\/11\/casa-tua-banner-c-274.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-106-layer-7\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.instagram.com\/theshelfaruba\/\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:70;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:4000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/05\/the-shel-ad-content-unit.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-1061\" data-title=\"Slide\" data-duration=\"16000ms\" data-anim=\"adpr:false;ms:70;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"UN OPORTUNIDAD DESTINA PA JENNIFER LOPEZ NA SUISA\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-1061-layer-0\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/web.facebook.com\/profile.php?id=61573929849977\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:12000;sp:70;sR:12000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sp:70;sR:7930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2025\/05\/Hit-94-banner-c.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-1061-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.garagecentraal.com\/gac-motor\/aion-ut\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:4000;sp:70;sR:4000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:8000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/05\/GU_-_FocusBanner_550x100.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-1061-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:8000;sp:70;sR:8000;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:12000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2020\/11\/casa-tua-banner-c-274.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-21-slide-1061-layer-7\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/www.instagram.com\/theshelfaruba\/\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:550px;h:110px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sp:70;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:4000;sp:70;sR:3930;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"550\" height=\"110\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/05\/the-shel-ad-content-unit.jpg\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_21_2',rl:[1240,1024,778,480],el:[110],gw:[550],gh:[110],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider212\"]!==undefined) {window.RS_MODULES.modules[\"revslider212\"].once = false;window.revapi21 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"931\" src=\"https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/fullsizeoutput_123b-1024x931.jpg\" alt=\"\" class=\"wp-image-26955\" srcset=\"https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/fullsizeoutput_123b-1024x931.jpg 1024w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/fullsizeoutput_123b-300x273.jpg 300w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/fullsizeoutput_123b-768x698.jpg 768w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/fullsizeoutput_123b-696x633.jpg 696w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/fullsizeoutput_123b-1068x971.jpg 1068w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/fullsizeoutput_123b-462x420.jpg 462w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/fullsizeoutput_123b-500x455.jpg 500w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/fullsizeoutput_123b-800x727.jpg 800w, https:\/\/focus.aw\/wp-content\/uploads\/2023\/03\/fullsizeoutput_123b.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Despues di a caba su Bachelor, el a dicidi di continua pa haci un Master den \u2018Financial Economics\u2019. Jennifer a bay durante su Master haci un stage na Washington DC na e embahada Hulandes y eynan el a cera amistad cu un mucha muhe di Uruguay, cu el a keda den contact cu ne ora el a regresa Hulanda. E ta e persona cu a bis\u2019e: \u201cDicon bo no ta aplica na Zurich, eynan tin un hopi bon calidad di bida\u201d. Awendia ora e wak bek e ta conclui cu si e no a haci e stage na Washington DC, e no lo ta eherciendo su carera profesional na Suisa. <\/p>\n\n\n\n<p>Lesa e entrevista di Jennifer Lopez cu ta duna entre otro su opinion di kico a yud\u2019e mas pa haci un carera como hende muhe. Focus Digital Magazine di maart ta accesibel gratis a traves di Apple <a href=\"https:\/\/apps.apple.com\/app\/id1525253258\" target=\"_blank\" rel=\"noreferrer noopener\">iStore<\/a>, Android Google <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.dot1tech.focus_magazine\" target=\"_blank\" rel=\"noreferrer noopener\">Play Store<\/a> y <a href=\"https:\/\/focus.aw\/index.php\/digital\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.focus.aw<\/a> (Menu Tab FOCUS DIGITAL).<\/p>\n\n\n\n\n\t\t\t<!-- START Banner Focus Digital aw REVOLUTION SLIDER 6.7.38 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_24_3_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;max-width:1350px;\">\n\t\t\t\t<rs-module id=\"rev_slider_24_3\" style=\"\" data-version=\"6.7.38\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-126\" data-title=\"Slide\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"UN OPORTUNIDAD DESTINA PA JENNIFER LOPEZ NA SUISA\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-24-slide-126-layer-3\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/focus.aw\/index.php\/digital\/\" target=\"_blank\" rel=\"noopener\"\n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:c;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:450px;h:563px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"sR:10;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8690;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/focus.aw\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"450\" height=\"563\" data-lazyload=\"\/\/focus.aw\/wp-content\/uploads\/2026\/05\/Feed-Web-340.gif\" data-no-retina> \n\t\t\t\t\t\t\t<\/a><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_24_3',rl:[1240,1024,778,480],el:[563],gw:[450],gh:[563],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider243\"]!==undefined) {window.RS_MODULES.modules[\"revslider243\"].once = false;window.revapi24 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n","protected":false},"excerpt":{"rendered":"<p>Jennifer ta trahando como un Senior Corporate Controller na Amcor, e compania multinacional mas grandi na Suisa, cu ta produci pakete pa diferente sector manera cuminda, medicina y tabaco. E ta revisa e parti financiero di un division pa haci analisis y wak si e compania ta \u2018meet\u2019 su presupuesto y obhetivonan financiero. Si lo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[2,46],"tags":[3526,874,105,3529,858,3530,3531,60,876,54,905,3060,3525,906,1343,3527,877,776,179,3535,3534,3528,3532,3533],"class_list":{"0":"post-26952","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured","8":"category-news-flash","9":"tag-amcor","10":"tag-apple","11":"tag-aruba","12":"tag-colegio-arubano","13":"tag-digital","14":"tag-erasmus-universiteit","15":"tag-financial-economics","16":"tag-focus","17":"tag-google","18":"tag-hulanda","19":"tag-jennifer","20":"tag-jennifer-lopez","21":"tag-lopez-3","22":"tag-lopez","23":"tag-magazine","24":"tag-meet","25":"tag-play","26":"tag-rotterdam","27":"tag-store","28":"tag-suisa","29":"tag-uruguay","30":"tag-vwo","31":"tag-washington-dc","32":"tag-zurich"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/posts\/26952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/comments?post=26952"}],"version-history":[{"count":4,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/posts\/26952\/revisions"}],"predecessor-version":[{"id":26960,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/posts\/26952\/revisions\/26960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/media\/26953"}],"wp:attachment":[{"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/media?parent=26952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/categories?post=26952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focus.aw\/index.php\/wp-json\/wp\/v2\/tags?post=26952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}